{"id":316,"date":"2019-07-11T16:28:32","date_gmt":"2019-07-11T16:28:32","guid":{"rendered":"https:\/\/sandovalpllc.com\/es\/?p=316"},"modified":"2023-10-03T21:58:07","modified_gmt":"2023-10-03T21:58:07","slug":"valor-de-mi-caso-de-accidente-auto","status":"publish","type":"post","link":"https:\/\/sandovalpllc.com\/es\/valor-de-mi-caso-de-accidente-auto\/","title":{"rendered":"\u00bfCu\u00e1nto vale mi caso de accidente de auto?"},"content":{"rendered":"<h2>El valor de su caso de accidente automovil\u00edstico (lesiones personales) depende de la extensi\u00f3n de sus lesiones<\/h2>\n<p>&#8230;<strong>Y, NEGLIGENCIA (NO SEGUIR LAS NORMAS DE LA CARRETERA)<\/strong><\/p>\n<p>Cuando usted ha sufrido una lesi\u00f3n grave en un <a href=\"\/es\/abogado-accidentes-de-auto\/\" rel=\"noopener noreferrer\" target=\"_blank\">accidente de auto<\/a>, tiene que demostrar que el otro conductor tuvo m\u00e1s culpa que usted en causar el choque y que las lesiones que sufri\u00f3 est\u00e1n relacionadas con el choque. Para determinar si usted tiene un BUEN CASO contra el otro conductor, usted necesita establecer que el otro conductor fue <strong>negligente y no sigui\u00f3 las reglas de la carretera. <\/strong><\/p>\n<h3>\u00a1Un Abogado de Accidentes Automovil\u00edsticos de Texas Puede Ayudar!<\/h3>\n<p>Determinar la negligencia es una tarea que recae en su abogado, pero adem\u00e1s de confiar en nuestra experiencia con casos anteriores, su abogado va a confiar en su recuerdo, declaraciones de testigos, informes de accidentes, fotograf\u00edas y cualquier otra informaci\u00f3n disponible. A veces, si la informaci\u00f3n disponible no es suficiente para concluir que el otro conductor fue negligente, pero es su fuerte creencia que el otro conductor fue culpable, una demanda tendr\u00e1 que ser presentada para ayudar a establecer la responsabilidad.\u00a0 Por lo tanto, es importante entender c\u00f3mo una v\u00edctima de accidente puede probar que las lesiones resultaron de la negligencia del otro conductor, pero usted querr\u00e1 asegurarse de consultar con un abogado de lesiones laborales para determinar si tambi\u00e9n puede ser apoyado por la ley de negligencia. \u00a1Llame a la Firma de Abogados Sandoval al <strong><a href=\"tel:+13463477777\" class=\"click-to-call-body\">(346) 347-7777<\/a><\/strong> y p\u00f3nganos a trabajar para usted!<\/p>\n<h3>Negligencia en un caso de accidente de auto<\/h3>\n<p>Los conductores de Texas tienen el <strong>deber<\/strong> de seguir las reglas del camino. Si no ejercen el cuidado ordinario en su conducci\u00f3n, se puede demostrar la negligencia de ese conductor. Esto se puede demostrar de varias maneras. Por ejemplo, ese conductor podr\u00eda haber fallado en mantener una vigilancia adecuada; fallado en controlar su velocidad; fallado en ceder el paso; fallado en conducir a una velocidad razonable o fallado en mantener el control del veh\u00edculo que estaban conduciendo.<\/p>\n<p>Si el otro conductor no ha ejercido el cuidado ordinario en la operaci\u00f3n de su veh\u00edculo, podr\u00edan haber <strong>violado<\/strong> la obligaci\u00f3n que tienen con el p\u00fablico en general en las carreteras.<\/p>\n<p>Si el otro conductor ha incumplido su deber de ejercer el cuidado ordinario al conducir, el siguiente paso es conectar las lesiones y los da\u00f1os con la lesi\u00f3n espec\u00edfica que causa el accidente automovil\u00edstico. Si sus lesiones pueden ser atribuidas al incidente, esto puede ser suficiente para concluir que hay un caso defendible contra el otro conductor.<\/p>\n<h3>\u00bfQU\u00c9 DA\u00d1OS SON RECUPERABLES EN UN CASO DE ACCIDENTE AUTOMOVIL\u00cdSTICO?<\/h3>\n<p>La determinaci\u00f3n de lo que usted puede recuperar en su caso de accidente automovil\u00edstico debe ser discutido con su abogado de lesiones personales. Debido a que cada caso es diferente, es importante entender que la capacidad de su abogado para probar sus da\u00f1os depender\u00e1 de sus lesiones y de si se espera que usted se recupere completamente. Por lo general, en un caso de accidente automovil\u00edstico, un demandante (persona lesionada) podr\u00eda tener derecho a una indemnizaci\u00f3n por los siguientes da\u00f1os y perjuicios:<\/p>\n<ul>\n<li><strong>Gastos M\u00e9dicos (Pasados y Futuros) <\/strong><\/li>\n<li><strong>P\u00e9rdida de ingresos\/capacidad de ganancia (pasado y futuro)<\/strong><\/li>\n<li><strong>Dolor F\u00edsico y Angustia Mental (Pasado y Futuro) <\/strong><\/li>\n<li><strong>Deterioro F\u00edsico <\/strong><\/li>\n<li><strong>Desfiguraci\u00f3n<\/strong><\/li>\n<\/ul>\n<p>Tener un previo entendimiento sobre qu\u00e9 reclamos puede hacer contra el otro conductor le ayudar\u00e1 cuando est\u00e9 tratando con el ajustador de seguros d\u00edas despu\u00e9s del accidente. Soy el Abogado de Accidentes de Autom\u00f3viles de Houston, H\u00e9ctor Sandoval, \u00a1y me enfoco en encontrar las respuestas para usted r\u00e1pidamente en un caso de accidente automovil\u00edstico! He representado a tejanos heridos en todo tipo de casos de choques de autos y camiones grandes. Mi equipo trabaja r\u00e1pidamente, y nos aseguramos de que todas las pruebas aseguren que su caso est\u00e1 preservado.<\/p>\n<p>\u00a1Llame a la Firma de Abogados Sandoval al <strong><a href=\"tel:+13463477777\" class=\"click-to-call-body\">(346) 347-7777<\/a><\/strong> y p\u00f3nganos a trabajar para usted!<\/p>\n<h3>Cada 7 d\u00edas, un promedio de 2,777 accidentes automovil\u00edsticos ocurren en Houston<\/h3>\n<p><iframe class=\"lazy-load\" width=\"100%\" height=\"450\" data-src=\"https:\/\/www.youtube.com\/embed\/vMTWEMs31bk?list=PLYoxLwZEZVozAaabOTR2qpcSEDxlQwfO9&#038;index=2\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El valor de su caso de accidente automovil\u00edstico (lesiones personales) depende de la extensi\u00f3n de sus lesiones &#8230;Y, NEGLIGENCIA (NO SEGUIR LAS NORMAS DE LA CARRETERA) Cuando usted ha sufrido una lesi\u00f3n grave en un accidente de auto, tiene que demostrar que el otro conductor tuvo m\u00e1s culpa que usted en causar el choque y&#8230; <a href=\"https:\/\/sandovalpllc.com\/es\/valor-de-mi-caso-de-accidente-auto\/\" class=\"learn-btn\">Continue Reading<\/a><\/p>\n","protected":false},"author":1,"featured_media":317,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[5,3],"tags":[],"class_list":["post-316","post","type-post","status-publish","format-standard","has-post-thumbnail","category-accidentes-de-trafico","category-blog","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfCu\u00e1nto vale mi caso de accidente automovil\u00edstico?<\/title>\n<meta name=\"description\" content=\"El valor de su caso de accidente automovil\u00edstico (lesiones personales) depende de la extensi\u00f3n de sus lesiones...Y, NEGLIGENCIA\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sandovalpllc.com\/es\/valor-de-mi-caso-de-accidente-auto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfCu\u00e1nto vale mi caso de accidente automovil\u00edstico?\" \/>\n<meta property=\"og:description\" content=\"El valor de su caso de accidente automovil\u00edstico (lesiones personales) depende de la extensi\u00f3n de sus lesiones...Y, NEGLIGENCIA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sandovalpllc.com\/es\/valor-de-mi-caso-de-accidente-auto\/\" \/>\n<meta property=\"og:site_name\" content=\"Bufete de Abogados Sandoval Da\u00f1os Personales y Muerte Injusta\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-11T16:28:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-03T21:58:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sandovalpllc.com\/es\/wp-content\/uploads\/sites\/2\/2019\/07\/valor-de-mi-caso-de-accidente-auto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"532\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sandoval\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"sandoval\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sandovalpllc.com\\\/es\\\/valor-de-mi-caso-de-accidente-auto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sandovalpllc.com\\\/es\\\/valor-de-mi-caso-de-accidente-auto\\\/\"},\"author\":{\"name\":\"sandoval\",\"@id\":\"https:\\\/\\\/sandovalpllc.com\\\/es\\\/#\\\/schema\\\/person\\\/66c14e83205199c77967875d13b2ea12\"},\"headline\":\"\u00bfCu\u00e1nto vale mi caso de accidente de auto?\",\"datePublished\":\"2019-07-11T16:28:32+00:00\",\"dateModified\":\"2023-10-03T21:58:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sandovalpllc.com\\\/es\\\/valor-de-mi-caso-de-accidente-auto\\\/\"},\"wordCount\":713,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/sandovalpllc.com\\\/es\\\/valor-de-mi-caso-de-accidente-auto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sandovalpllc.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/valor-de-mi-caso-de-accidente-auto.jpg\",\"articleSection\":[\"Accidentes De Auto\",\"Blog De Sandoval\"],\"inLanguage\":\"es-PE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sandovalpllc.com\\\/es\\\/valor-de-mi-caso-de-accidente-auto\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sandovalpllc.com\\\/es\\\/valor-de-mi-caso-de-accidente-auto\\\/\",\"url\":\"https:\\\/\\\/sandovalpllc.com\\\/es\\\/valor-de-mi-caso-de-accidente-auto\\\/\",\"name\":\"\u00bfCu\u00e1nto vale mi caso de accidente automovil\u00edstico?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sandovalpllc.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sandovalpllc.com\\\/es\\\/valor-de-mi-caso-de-accidente-auto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sandovalpllc.com\\\/es\\\/valor-de-mi-caso-de-accidente-auto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sandovalpllc.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/valor-de-mi-caso-de-accidente-auto.jpg\",\"datePublished\":\"2019-07-11T16:28:32+00:00\",\"dateModified\":\"2023-10-03T21:58:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sandovalpllc.com\\\/es\\\/#\\\/schema\\\/person\\\/66c14e83205199c77967875d13b2ea12\"},\"description\":\"El valor de su caso de accidente automovil\u00edstico (lesiones personales) depende de la extensi\u00f3n de sus lesiones...Y, NEGLIGENCIA\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sandovalpllc.com\\\/es\\\/valor-de-mi-caso-de-accidente-auto\\\/#breadcrumb\"},\"inLanguage\":\"es-PE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sandovalpllc.com\\\/es\\\/valor-de-mi-caso-de-accidente-auto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-PE\",\"@id\":\"https:\\\/\\\/sandovalpllc.com\\\/es\\\/valor-de-mi-caso-de-accidente-auto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sandovalpllc.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/valor-de-mi-caso-de-accidente-auto.jpg\",\"contentUrl\":\"https:\\\/\\\/sandovalpllc.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/valor-de-mi-caso-de-accidente-auto.jpg\",\"width\":800,\"height\":532,\"caption\":\"\u00bfCu\u00e1nto vale mi caso de accidente automovil\u00edstico?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sandovalpllc.com\\\/es\\\/valor-de-mi-caso-de-accidente-auto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/sandovalpllc.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfCu\u00e1nto vale mi caso de accidente de auto?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sandovalpllc.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/sandovalpllc.com\\\/es\\\/\",\"name\":\"Bufete de Abogados Sandoval Da\u00f1os Personales y Muerte Injusta\",\"description\":\"Just another Sandoval Law Firm, PLLC Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sandovalpllc.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-PE\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sandovalpllc.com\\\/es\\\/#\\\/schema\\\/person\\\/66c14e83205199c77967875d13b2ea12\",\"name\":\"sandoval\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-PE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25babf28bdacfb1326524e8a7811565c488118fe19c82e66923ab3b9171b07b9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25babf28bdacfb1326524e8a7811565c488118fe19c82e66923ab3b9171b07b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25babf28bdacfb1326524e8a7811565c488118fe19c82e66923ab3b9171b07b9?s=96&d=mm&r=g\",\"caption\":\"sandoval\"},\"url\":\"https:\\\/\\\/sandovalpllc.com\\\/es\\\/author\\\/johnny\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfCu\u00e1nto vale mi caso de accidente automovil\u00edstico?","description":"El valor de su caso de accidente automovil\u00edstico (lesiones personales) depende de la extensi\u00f3n de sus lesiones...Y, NEGLIGENCIA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sandovalpllc.com\/es\/valor-de-mi-caso-de-accidente-auto\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfCu\u00e1nto vale mi caso de accidente automovil\u00edstico?","og_description":"El valor de su caso de accidente automovil\u00edstico (lesiones personales) depende de la extensi\u00f3n de sus lesiones...Y, NEGLIGENCIA","og_url":"https:\/\/sandovalpllc.com\/es\/valor-de-mi-caso-de-accidente-auto\/","og_site_name":"Bufete de Abogados Sandoval Da\u00f1os Personales y Muerte Injusta","article_published_time":"2019-07-11T16:28:32+00:00","article_modified_time":"2023-10-03T21:58:07+00:00","og_image":[{"width":800,"height":532,"url":"https:\/\/sandovalpllc.com\/es\/wp-content\/uploads\/sites\/2\/2019\/07\/valor-de-mi-caso-de-accidente-auto.jpg","type":"image\/jpeg"}],"author":"sandoval","twitter_card":"summary_large_image","twitter_misc":{"Written by":"sandoval","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sandovalpllc.com\/es\/valor-de-mi-caso-de-accidente-auto\/#article","isPartOf":{"@id":"https:\/\/sandovalpllc.com\/es\/valor-de-mi-caso-de-accidente-auto\/"},"author":{"name":"sandoval","@id":"https:\/\/sandovalpllc.com\/es\/#\/schema\/person\/66c14e83205199c77967875d13b2ea12"},"headline":"\u00bfCu\u00e1nto vale mi caso de accidente de auto?","datePublished":"2019-07-11T16:28:32+00:00","dateModified":"2023-10-03T21:58:07+00:00","mainEntityOfPage":{"@id":"https:\/\/sandovalpllc.com\/es\/valor-de-mi-caso-de-accidente-auto\/"},"wordCount":713,"commentCount":0,"image":{"@id":"https:\/\/sandovalpllc.com\/es\/valor-de-mi-caso-de-accidente-auto\/#primaryimage"},"thumbnailUrl":"https:\/\/sandovalpllc.com\/es\/wp-content\/uploads\/sites\/2\/2019\/07\/valor-de-mi-caso-de-accidente-auto.jpg","articleSection":["Accidentes De Auto","Blog De Sandoval"],"inLanguage":"es-PE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sandovalpllc.com\/es\/valor-de-mi-caso-de-accidente-auto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sandovalpllc.com\/es\/valor-de-mi-caso-de-accidente-auto\/","url":"https:\/\/sandovalpllc.com\/es\/valor-de-mi-caso-de-accidente-auto\/","name":"\u00bfCu\u00e1nto vale mi caso de accidente automovil\u00edstico?","isPartOf":{"@id":"https:\/\/sandovalpllc.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sandovalpllc.com\/es\/valor-de-mi-caso-de-accidente-auto\/#primaryimage"},"image":{"@id":"https:\/\/sandovalpllc.com\/es\/valor-de-mi-caso-de-accidente-auto\/#primaryimage"},"thumbnailUrl":"https:\/\/sandovalpllc.com\/es\/wp-content\/uploads\/sites\/2\/2019\/07\/valor-de-mi-caso-de-accidente-auto.jpg","datePublished":"2019-07-11T16:28:32+00:00","dateModified":"2023-10-03T21:58:07+00:00","author":{"@id":"https:\/\/sandovalpllc.com\/es\/#\/schema\/person\/66c14e83205199c77967875d13b2ea12"},"description":"El valor de su caso de accidente automovil\u00edstico (lesiones personales) depende de la extensi\u00f3n de sus lesiones...Y, NEGLIGENCIA","breadcrumb":{"@id":"https:\/\/sandovalpllc.com\/es\/valor-de-mi-caso-de-accidente-auto\/#breadcrumb"},"inLanguage":"es-PE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sandovalpllc.com\/es\/valor-de-mi-caso-de-accidente-auto\/"]}]},{"@type":"ImageObject","inLanguage":"es-PE","@id":"https:\/\/sandovalpllc.com\/es\/valor-de-mi-caso-de-accidente-auto\/#primaryimage","url":"https:\/\/sandovalpllc.com\/es\/wp-content\/uploads\/sites\/2\/2019\/07\/valor-de-mi-caso-de-accidente-auto.jpg","contentUrl":"https:\/\/sandovalpllc.com\/es\/wp-content\/uploads\/sites\/2\/2019\/07\/valor-de-mi-caso-de-accidente-auto.jpg","width":800,"height":532,"caption":"\u00bfCu\u00e1nto vale mi caso de accidente automovil\u00edstico?"},{"@type":"BreadcrumbList","@id":"https:\/\/sandovalpllc.com\/es\/valor-de-mi-caso-de-accidente-auto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/sandovalpllc.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfCu\u00e1nto vale mi caso de accidente de auto?"}]},{"@type":"WebSite","@id":"https:\/\/sandovalpllc.com\/es\/#website","url":"https:\/\/sandovalpllc.com\/es\/","name":"Bufete de Abogados Sandoval Da\u00f1os Personales y Muerte Injusta","description":"Just another Sandoval Law Firm, PLLC Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sandovalpllc.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-PE"},{"@type":"Person","@id":"https:\/\/sandovalpllc.com\/es\/#\/schema\/person\/66c14e83205199c77967875d13b2ea12","name":"sandoval","image":{"@type":"ImageObject","inLanguage":"es-PE","@id":"https:\/\/secure.gravatar.com\/avatar\/25babf28bdacfb1326524e8a7811565c488118fe19c82e66923ab3b9171b07b9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/25babf28bdacfb1326524e8a7811565c488118fe19c82e66923ab3b9171b07b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/25babf28bdacfb1326524e8a7811565c488118fe19c82e66923ab3b9171b07b9?s=96&d=mm&r=g","caption":"sandoval"},"url":"https:\/\/sandovalpllc.com\/es\/author\/johnny\/"}]}},"_links":{"self":[{"href":"https:\/\/sandovalpllc.com\/es\/wp-json\/wp\/v2\/posts\/316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sandovalpllc.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sandovalpllc.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sandovalpllc.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sandovalpllc.com\/es\/wp-json\/wp\/v2\/comments?post=316"}],"version-history":[{"count":0,"href":"https:\/\/sandovalpllc.com\/es\/wp-json\/wp\/v2\/posts\/316\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sandovalpllc.com\/es\/wp-json\/wp\/v2\/media\/317"}],"wp:attachment":[{"href":"https:\/\/sandovalpllc.com\/es\/wp-json\/wp\/v2\/media?parent=316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sandovalpllc.com\/es\/wp-json\/wp\/v2\/categories?post=316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sandovalpllc.com\/es\/wp-json\/wp\/v2\/tags?post=316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}